{"id":354,"date":"2009-03-17T08:00:01","date_gmt":"2009-03-17T07:00:01","guid":{"rendered":"http:\/\/seguridadeninternet.wordpress.com\/?p=354"},"modified":"2009-03-17T08:00:01","modified_gmt":"2009-03-17T07:00:01","slug":"lectores-web-de-rss","status":"publish","type":"post","link":"https:\/\/www.montejo.biz\/blog\/2009\/03\/17\/lectores-web-de-rss\/","title":{"rendered":"Lectores web de RSS"},"content":{"rendered":"<div id=\"post-entry-excerpt-354\" class=\"entry-part\"><p>Estas aplicaciones aportan movilidad y flexibilidad a la sindicaci\u00f3n de contenidos<\/p>\n<p>El RSS, el formato que sirve para estar al d\u00eda de las noticias de diversos blogs y medios, entre ellos CONSUMER EROSKI, se puede consultar desde la propia Web, sin necesidad de instalar ning\u00fan programa en el ordenador. Igual que sucede con el correo electr\u00f3nico, diversos sitios ofrecen aplicaciones que permiten gestionar este servicio desde Internet e importar las suscripciones registradas en la aplicaci\u00f3n de escritorio que se utilice.<\/p>\n<p><a href=\"http:\/\/www.consumer.es\/web\/es\/tecnologia\/internet\/2009\/03\/04\/183361.php\" target=\"_blank\">Enlace<\/a><\/p>\n\n\t\t\t\t\t\t\t<p style=\" color: #999999;\">If you found an error, highlight it and press <strong>Shift + E<\/strong> or <a href=\"#\" class=\"enp-report\"><strong>pulsa aqu\u00ed<\/strong><\/a> to inform us.<\/p>\n\t\t\t\t\t\t<\/div><div id=\"post-footer-354\" class=\"post-footer clear\"><\/div>","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>Estas aplicaciones aportan movilidad y flexibilidad a la sindicaci\u00f3n de contenidos El RSS, el formato que sirve para estar al d\u00eda de las noticias de <a class=\"mh-excerpt-more\" href=\"https:\/\/www.montejo.biz\/blog\/2009\/03\/17\/lectores-web-de-rss\/\" title=\"Lectores web de RSS\">[&#8230;]<\/a><\/p>\n<\/div>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"footnotes":""},"categories":[54],"tags":[161],"class_list":["post-354","post","type-post","status-publish","format-standard","hentry","category-rss","tag-rss"],"_links":{"self":[{"href":"https:\/\/www.montejo.biz\/blog\/wp-json\/wp\/v2\/posts\/354","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.montejo.biz\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.montejo.biz\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.montejo.biz\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.montejo.biz\/blog\/wp-json\/wp\/v2\/comments?post=354"}],"version-history":[{"count":0,"href":"https:\/\/www.montejo.biz\/blog\/wp-json\/wp\/v2\/posts\/354\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.montejo.biz\/blog\/wp-json\/wp\/v2\/media?parent=354"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.montejo.biz\/blog\/wp-json\/wp\/v2\/categories?post=354"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.montejo.biz\/blog\/wp-json\/wp\/v2\/tags?post=354"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}