{"id":5737,"date":"2013-04-12T15:08:00","date_gmt":"2013-04-12T14:08:00","guid":{"rendered":"http:\/\/www.montejo.biz\/blog\/?p=5737"},"modified":"2013-04-07T19:22:04","modified_gmt":"2013-04-07T18:22:04","slug":"control-de-procesos-en-windows","status":"publish","type":"post","link":"https:\/\/www.montejo.biz\/blog\/2013\/04\/12\/control-de-procesos-en-windows\/","title":{"rendered":"Control de procesos en Windows"},"content":{"rendered":"<div id=\"post-entry-excerpt-5737\" class=\"entry-part\"><p>Windows, al contrario que Linux, nunca ha tenido un servicio de control de procesos digno de tal nombre, quiz\u00e1s a partir de Windows 7.<\/p>\n<p><a href=\"http:\/\/www.montejo.biz\/blog\/wp-content\/uploads\/2013\/04\/07-04-2013-20-05-12.gif\"><img loading=\"lazy\" decoding=\"async\" style=\"background-image: none; padding-top: 0px; padding-left: 0px; display: inline; padding-right: 0px; border: 0px;\" title=\"07-04-2013 20-05-12\" alt=\"07-04-2013 20-05-12\" src=\"http:\/\/www.montejo.biz\/blog\/wp-content\/uploads\/2013\/04\/07-04-2013-20-05-12_thumb.gif\" width=\"500\" height=\"347\" border=\"0\" \/><\/a><\/p>\n<p>Si vamos al programa Administrador de tareas y vemos las propiedades de un proceso en Windows nos aparece una ventana como esta:<\/p>\n<p><!--more--><a href=\"http:\/\/www.montejo.biz\/blog\/wp-content\/uploads\/2013\/04\/07-04-2013-19-19-44.gif\"><img loading=\"lazy\" decoding=\"async\" style=\"background-image: none; padding-top: 0px; padding-left: 0px; display: inline; padding-right: 0px; border: 0px;\" title=\"07-04-2013 19-19-44\" alt=\"07-04-2013 19-19-44\" src=\"http:\/\/www.montejo.biz\/blog\/wp-content\/uploads\/2013\/04\/07-04-2013-19-19-44_thumb.gif\" width=\"385\" height=\"500\" border=\"0\" \/><\/a><\/p>\n<p>Aparece, por defecto, la pesta\u00f1a General con la informaci\u00f3n que vemos.<\/p>\n<p>Tambi\u00e9n hay otras 5 pesta\u00f1as (qu\u00e9 derroche de pesta\u00f1as para la m\u00ednima informaci\u00f3n que hay en cada una\u2026).<\/p>\n<p>La que me parece m\u00e1s pr\u00e1ctica de las 5 que quedan es la de Compatibilidad:<\/p>\n<p><a href=\"http:\/\/www.montejo.biz\/blog\/wp-content\/uploads\/2013\/04\/07-04-2013-19-23-35.gif\"><img loading=\"lazy\" decoding=\"async\" style=\"background-image: none; padding-top: 0px; padding-left: 0px; display: inline; padding-right: 0px; border: 0px;\" title=\"07-04-2013 19-23-35\" alt=\"07-04-2013 19-23-35\" src=\"http:\/\/www.montejo.biz\/blog\/wp-content\/uploads\/2013\/04\/07-04-2013-19-23-35_thumb.gif\" width=\"385\" height=\"500\" border=\"0\" \/><\/a><\/p>\n<p>Por medio de estas opciones podemos ejecutar este programa con una versi\u00f3n anterior de Windows, con una configuraci\u00f3n simplificada o como administrador.<\/p>\n<p>Voy a explicar un programa que nos presenta mucha m\u00e1s informaci\u00f3n de los procesos de Windows, permiti\u00e9ndonos interactuar con ellos de forma mucho m\u00e1s profunda.<\/p>\n<p><a href=\"http:\/\/www.montejo.biz\/blog\/wp-content\/uploads\/2013\/04\/07-04-2013-20-07-03.gif\"><img loading=\"lazy\" decoding=\"async\" style=\"background-image: none; padding-top: 0px; padding-left: 0px; display: inline; padding-right: 0px; border: 0px;\" title=\"07-04-2013 20-07-03\" alt=\"07-04-2013 20-07-03\" src=\"http:\/\/www.montejo.biz\/blog\/wp-content\/uploads\/2013\/04\/07-04-2013-20-07-03_thumb.gif\" width=\"422\" height=\"400\" border=\"0\" \/><\/a><\/p>\n<p>Fuente: <a href=\"https:\/\/www.google.es\/url?sa=i&amp;rct=j&amp;q=&amp;esrc=s&amp;source=images&amp;cd=&amp;cad=rja&amp;docid=efaQkCMtpuptoM&amp;tbnid=cuIvjC-BJrlVVM:&amp;ved=0CAIQjBw&amp;url=http%3A%2F%2Fimg.scoop.it%2FkRG4gd0d1V9UfUD_Rnl1Xjl72eJkfbmt4t8yenImKBVaiQDB_Rd1H6kmuBWtceBJ&amp;ei=0bVhUaXlMYKxPO2XgIAF&amp;bvm=bv.44770516,d.bGE&amp;psig=AFQjCNHJ5qAIWph-U-NBzFL0WFQq7oAHYg&amp;ust=1365444392745779\" target=\"_blank\">www.scoop.it<\/a><\/p>\n<p><strong>Programa<\/strong><\/p>\n<p>El programa se llama <em>Process Explorer<\/em> y se puede descargar de la direcci\u00f3n <a title=\"http:\/\/download.sysinternals.com\/files\/ProcessExplorer.zip\" href=\"http:\/\/download.sysinternals.com\/files\/ProcessExplorer.zip\" target=\"_blank\">http:\/\/download.sysinternals.com\/files\/ProcessExplorer.zip<\/a>.<\/p>\n<p>Una vez descargado y descomprimido, podemos utilizarlo (es portable).<\/p>\n<p><a href=\"http:\/\/www.montejo.biz\/blog\/wp-content\/uploads\/2013\/04\/07-04-2013-19-34-32.gif\"><img loading=\"lazy\" decoding=\"async\" style=\"background-image: none; padding-top: 0px; padding-left: 0px; display: inline; padding-right: 0px; border: 0px;\" title=\"07-04-2013 19-34-32\" alt=\"07-04-2013 19-34-32\" src=\"http:\/\/www.montejo.biz\/blog\/wp-content\/uploads\/2013\/04\/07-04-2013-19-34-32_thumb.gif\" width=\"484\" height=\"331\" border=\"0\" \/><\/a><\/p>\n<p>Aceptamos el acuerdo de licencia (\u00bfpero esto qu\u00e9 es?).<\/p>\n<p><a href=\"http:\/\/www.montejo.biz\/blog\/wp-content\/uploads\/2013\/04\/07-04-2013-19-39-37.gif\"><img loading=\"lazy\" decoding=\"async\" style=\"background-image: none; padding-top: 0px; padding-left: 0px; display: inline; padding-right: 0px; border: 0px;\" title=\"07-04-2013 19-39-37\" alt=\"07-04-2013 19-39-37\" src=\"http:\/\/www.montejo.biz\/blog\/wp-content\/uploads\/2013\/04\/07-04-2013-19-39-37_thumb.gif\" width=\"500\" height=\"375\" border=\"0\" \/><\/a><\/p>\n<p>Esta es la ventana que vemos al entrar al programa. Las columnas que vemos por defecto son:<\/p>\n<ul>\n<li>Proceso<\/li>\n<li>% CPU utilizado<\/li>\n<li>Bytes privados<\/li>\n<li>Memoria utilizada<\/li>\n<li>C\u00f3digo de proceso<\/li>\n<li>Descripci\u00f3n<\/li>\n<li>Compa\u00f1\u00eda<\/li>\n<\/ul>\n<p>Si pulsamos con el bot\u00f3n derecho del rat\u00f3n en un campo de la cabecera podemos elegir los campos que queramos ver.<\/p>\n<p><a href=\"http:\/\/www.montejo.biz\/blog\/wp-content\/uploads\/2013\/04\/07-04-2013-19-46-58.gif\"><img loading=\"lazy\" decoding=\"async\" style=\"background-image: none; padding-top: 0px; padding-left: 0px; display: inline; padding-right: 0px; border: 0px;\" title=\"07-04-2013 19-46-58\" alt=\"07-04-2013 19-46-58\" src=\"http:\/\/www.montejo.biz\/blog\/wp-content\/uploads\/2013\/04\/07-04-2013-19-46-58_thumb.gif\" width=\"359\" height=\"492\" border=\"0\" \/><\/a><\/p>\n<p>Dependiendo del tipo de proceso que sea podemos elegir la informaci\u00f3n que queramos ver de \u00e9l (hay 9 pesta\u00f1as para ir eligiendo campos).<\/p>\n<p>Si hacemos clic con el bot\u00f3n derecho del rat\u00f3n en un proceso, tenemos disponibles las siguientes opciones:<\/p>\n<p><a href=\"http:\/\/www.montejo.biz\/blog\/wp-content\/uploads\/2013\/04\/07-04-2013-19-51-42.gif\"><img loading=\"lazy\" decoding=\"async\" style=\"background-image: none; padding-top: 0px; padding-left: 0px; display: inline; padding-right: 0px; border: 0px;\" title=\"07-04-2013 19-51-42\" alt=\"07-04-2013 19-51-42\" src=\"http:\/\/www.montejo.biz\/blog\/wp-content\/uploads\/2013\/04\/07-04-2013-19-51-42_thumb.gif\" width=\"224\" height=\"258\" border=\"0\" \/><\/a><\/p>\n<p>Set Affinity\u2026 Elegimos las CPUs que pueden ejecutar el proceso.<\/p>\n<p>Set Priority. Elegir prioridad de ejecuci\u00f3n del proceso. Hay una gama de elecci\u00f3n mucho m\u00e1s amplia que con el Administrador de tareas.<\/p>\n<p><a href=\"http:\/\/www.montejo.biz\/blog\/wp-content\/uploads\/2013\/04\/07-04-2013-19-53-08.gif\"><img loading=\"lazy\" decoding=\"async\" style=\"background-image: none; padding-top: 0px; padding-left: 0px; display: inline; padding-right: 0px; border: 0px;\" title=\"07-04-2013 19-53-08\" alt=\"07-04-2013 19-53-08\" src=\"http:\/\/www.montejo.biz\/blog\/wp-content\/uploads\/2013\/04\/07-04-2013-19-53-08_thumb.gif\" width=\"331\" height=\"160\" border=\"0\" \/><\/a><\/p>\n<p>Kill Process. Mata el proceso.<\/p>\n<p>Kill Process Tree. Mata el proceso y todos los que dependen de \u00e9l (los hijos, nietos, etc.)<\/p>\n<p>Restart. Reinicia el proceso (lo termina y lo vuelve a iniciar).<\/p>\n<p>Suspend. Detiene el proceso.<\/p>\n<p>Create Dump. Volcado de memoria del proceso.<\/p>\n<p>Properties. Propiedades del proceso, todo un lujo asi\u00e1tico.<\/p>\n<p><a href=\"http:\/\/www.montejo.biz\/blog\/wp-content\/uploads\/2013\/04\/07-04-2013-19-55-02.gif\"><img loading=\"lazy\" decoding=\"async\" style=\"background-image: none; padding-top: 0px; padding-left: 0px; display: inline; padding-right: 0px; border: 0px;\" title=\"07-04-2013 19-55-02\" alt=\"07-04-2013 19-55-02\" src=\"http:\/\/www.montejo.biz\/blog\/wp-content\/uploads\/2013\/04\/07-04-2013-19-55-02_thumb.gif\" width=\"412\" height=\"500\" border=\"0\" \/><\/a><\/p>\n<p>11 pesta\u00f1as de informaci\u00f3n (ah\u00ed es nada). Aconsejo mirarlas una a una ya que hay un mont\u00f3n de informaci\u00f3n \u00fatil.<\/p>\n<p>Tambi\u00e9n podemos ver las dll\u2019s de un proceso, entre otras informaciones.<\/p>\n<p>En fin, te dejo para que investigues en los men\u00fas las opciones tan interesantes que contienen.<\/p>\n\n\t\t\t\t\t\t\t<p style=\" color: #999999;\">If you found an error, highlight it and press <strong>Shift + E<\/strong> or <a href=\"#\" class=\"enp-report\"><strong>pulsa aqu\u00ed<\/strong><\/a> to inform us.<\/p>\n\t\t\t\t\t\t<\/div><div id=\"post-footer-5737\" class=\"post-footer clear\"><\/div>","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>Windows, al contrario que Linux, nunca ha tenido un servicio de control de procesos digno de tal nombre, quiz\u00e1s a partir de Windows 7. Si <a class=\"mh-excerpt-more\" href=\"https:\/\/www.montejo.biz\/blog\/2013\/04\/12\/control-de-procesos-en-windows\/\" title=\"Control de procesos en Windows\">[&#8230;]<\/a><\/p>\n<\/div>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"footnotes":""},"categories":[52,55,64],"tags":[159,162,171],"class_list":["post-5737","post","type-post","status-publish","format-standard","hentry","category-programas","category-seguridad","category-windows","tag-programas","tag-seguridad","tag-windows"],"_links":{"self":[{"href":"https:\/\/www.montejo.biz\/blog\/wp-json\/wp\/v2\/posts\/5737","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.montejo.biz\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.montejo.biz\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.montejo.biz\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.montejo.biz\/blog\/wp-json\/wp\/v2\/comments?post=5737"}],"version-history":[{"count":1,"href":"https:\/\/www.montejo.biz\/blog\/wp-json\/wp\/v2\/posts\/5737\/revisions"}],"predecessor-version":[{"id":5738,"href":"https:\/\/www.montejo.biz\/blog\/wp-json\/wp\/v2\/posts\/5737\/revisions\/5738"}],"wp:attachment":[{"href":"https:\/\/www.montejo.biz\/blog\/wp-json\/wp\/v2\/media?parent=5737"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.montejo.biz\/blog\/wp-json\/wp\/v2\/categories?post=5737"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.montejo.biz\/blog\/wp-json\/wp\/v2\/tags?post=5737"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}